{"id":519,"date":"2026-01-13T01:28:15","date_gmt":"2026-01-13T00:28:15","guid":{"rendered":"https:\/\/urusegur.com\/?page_id=519"},"modified":"2026-01-31T02:42:29","modified_gmt":"2026-01-31T01:42:29","slug":"contacto","status":"publish","type":"page","link":"https:\/\/nomloop.com\/uy\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"<div class=\"bloque-encabezado\">\n<p>  <span class=\"subtitulo-seccion\">Atenci\u00f3n informativa y contacto general<\/span><\/p>\n<p class=\"texto-seccion\">\n    En <strong>Nomloop<\/strong> ponemos a disposici\u00f3n de los usuarios un canal de<br \/>\n    contacto para atender consultas relacionadas con el funcionamiento del<br \/>\n    directorio y la informaci\u00f3n publicada en el sitio web.\n  <\/p>\n<p class=\"texto-seccion\">\n    Nuestro equipo revisa cada solicitud de forma individual, ofreciendo<br \/>\n    respuestas claras y ajustadas al car\u00e1cter informativo de la plataforma.\n  <\/p>\n<\/div>\n<h2 class=\"titulo-seccion\"><span class=\"ez-toc-section\" id=\"Como_contactar_con_Nomloop\"><\/span>C\u00f3mo contactar con Nomloop<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p class=\"texto-seccion\">\n  Puedes ponerte en contacto con nosotros a trav\u00e9s de los siguientes medios:\n<\/p>\n<ul>\n<li>Mediante el formulario de contacto disponible en esta p\u00e1gina.<\/li>\n<li>Para consultas generales relacionadas con el sitio web.<\/li>\n<li>Para comunicaciones informativas o solicitudes de revisi\u00f3n de contenido.<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><style id=\"wpforms-css-vars-123\">\n\t\t\t\t#wpforms-123 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-123\"><form id=\"wpforms-form-123\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"123\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/uy\/wp-json\/wp\/v2\/pages\/519\" data-token=\"337c1b4cd164886b79ce79d5d9bb67d0\" data-token-time=\"1778679020\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-123-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Nombre <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-123-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-123-field_1-error\" required><label for=\"wpforms-123-field_1\" class=\"wpforms-field-sublabel after\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-123-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-123-field_1-last-error\" required><label for=\"wpforms-123-field_1-last\" class=\"wpforms-field-sublabel after\">Apellidos<\/label><\/div><\/div><\/fieldset><\/div>\t\t<div id=\"wpforms-123-field_4-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"4\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-123-field_4\" >electr\u00f3nico Nombre mensaje<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-123-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-123-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-123-field_2\">Correo electr\u00f3nico <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-123-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-123-field_2-error\" required><\/div><div id=\"wpforms-123-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-123-field_3\">Comentario o mensaje<\/label><textarea id=\"wpforms-123-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-123-field_3-error\" ><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-123-field_4-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-123-field_4-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-123-field_4-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"123\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/nomloop.com\/uy\/wp-json\/wp\/v2\/pages\/519\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-123\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nomloop.com\/uy\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/p>\n<h2 class=\"titulo-seccion\"><span class=\"ez-toc-section\" id=\"Tipo_de_consultas_que_atendemos\"><\/span>Tipo de consultas que atendemos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p class=\"texto-seccion\">\n  A trav\u00e9s de este canal atendemos consultas de car\u00e1cter informativo,<br \/>\n  incluyendo, entre otras:\n<\/p>\n<ul>\n<li>Informaci\u00f3n general sobre el funcionamiento del directorio.<\/li>\n<li>Solicitudes de correcci\u00f3n o actualizaci\u00f3n de fichas informativas.<\/li>\n<li>Consultas relacionadas con el uso del sitio web.<\/li>\n<li>Comunicaciones de profesionales o comercios interesados en aparecer en el directorio.<\/li>\n<li>Notificaciones relacionadas con contenidos publicados.<\/li>\n<\/ul>\n<h2 class=\"titulo-seccion\"><span class=\"ez-toc-section\" id=\"Alcance_del_contacto\"><\/span>Alcance del contacto<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p class=\"texto-seccion\">\n  <strong>Nomloop<\/strong> act\u00faa exclusivamente como un directorio informativo.<br \/>\n  No gestionamos directamente servicios esot\u00e9ricos ni intermediamos en la<br \/>\n  contrataci\u00f3n de profesionales o la venta de productos.\n<\/p>\n<p class=\"texto-seccion\">\n  Las consultas enviadas a trav\u00e9s de este formulario no constituyen una<br \/>\n  solicitud de asesoramiento profesional de ning\u00fan tipo.\n<\/p>\n<h2 class=\"titulo-seccion\"><span class=\"ez-toc-section\" id=\"Proteccion_de_datos_y_confidencialidad\"><\/span>Protecci\u00f3n de datos y confidencialidad<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p class=\"texto-seccion\">\n  Los datos facilitados a trav\u00e9s de este formulario ser\u00e1n tratados de forma<br \/>\n  confidencial y utilizados \u00fanicamente para gestionar la consulta realizada,<br \/>\n  conforme a la normativa vigente en materia de protecci\u00f3n de datos.\n<\/p>\n<p class=\"texto-seccion\">\n  Puedes ampliar esta informaci\u00f3n consultando nuestra<br \/>\n  <strong>Pol\u00edtica de Privacidad<\/strong>.\n<\/p>\n<div class=\"resumen-destacado\">\n  Contacta con <strong>Nomloop<\/strong> para consultas informativas relacionadas<br \/>\n  con el directorio de servicios esot\u00e9ricos y el contenido del sitio web.\n<\/div>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_80 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Conenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nomloop.com\/uy\/contacto\/#Como_contactar_con_Nomloop\" >C\u00f3mo contactar con Nomloop<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nomloop.com\/uy\/contacto\/#Tipo_de_consultas_que_atendemos\" >Tipo de consultas que atendemos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nomloop.com\/uy\/contacto\/#Alcance_del_contacto\" >Alcance del contacto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nomloop.com\/uy\/contacto\/#Proteccion_de_datos_y_confidencialidad\" >Protecci\u00f3n de datos y confidencialidad<\/a><\/li><\/ul><\/nav><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Atenci\u00f3n informativa y contacto general En Nomloop ponemos a disposici\u00f3n de los usuarios un canal de contacto para atender consultas relacionadas con el funcionamiento del directorio y la informaci\u00f3n publicada en el sitio web. Nuestro equipo revisa cada solicitud de forma individual, ofreciendo respuestas claras y ajustadas al car\u00e1cter informativo de la plataforma. C\u00f3mo contactar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":509,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-519","page","type-page","status-publish","has-post-thumbnail","hentry"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contacto | NomLoop<\/title>\n<meta name=\"description\" content=\"Contacta con Nomloop para consultas informativas, correcciones de fichas o informaci\u00f3n sobre el directorio de servicios esot\u00e9ricos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nomloop.com\/uy\/contacto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contacto | NomLoop\" \/>\n<meta property=\"og:description\" content=\"Contacta con Nomloop para consultas informativas, correcciones de fichas o informaci\u00f3n sobre el directorio de servicios esot\u00e9ricos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nomloop.com\/uy\/contacto\/\" \/>\n<meta property=\"og:site_name\" content=\"Uruguay\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-31T01:42:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/URUSEGUR_Contacto.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"572\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nomloop.com\/uy\/contacto\/\",\"url\":\"https:\/\/nomloop.com\/uy\/contacto\/\",\"name\":\"Contacto | NomLoop\",\"isPartOf\":{\"@id\":\"https:\/\/nomloop.com\/uy\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nomloop.com\/uy\/contacto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nomloop.com\/uy\/contacto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/URUSEGUR_Contacto.webp\",\"datePublished\":\"2026-01-13T00:28:15+00:00\",\"dateModified\":\"2026-01-31T01:42:29+00:00\",\"description\":\"Contacta con Nomloop para consultas informativas, correcciones de fichas o informaci\u00f3n sobre el directorio de servicios esot\u00e9ricos.\",\"breadcrumb\":{\"@id\":\"https:\/\/nomloop.com\/uy\/contacto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nomloop.com\/uy\/contacto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nomloop.com\/uy\/contacto\/#primaryimage\",\"url\":\"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/URUSEGUR_Contacto.webp\",\"contentUrl\":\"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/URUSEGUR_Contacto.webp\",\"width\":1536,\"height\":572,\"caption\":\"Pre-Contacto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nomloop.com\/uy\/contacto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/nomloop.com\/uy\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contacto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nomloop.com\/uy\/#website\",\"url\":\"https:\/\/nomloop.com\/uy\/\",\"name\":\"Uruguay\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nomloop.com\/uy\/#\/schema\/person\/31d96ea0e6c72ae23ec4f725e949fdab\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nomloop.com\/uy\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/nomloop.com\/uy\/#\/schema\/person\/31d96ea0e6c72ae23ec4f725e949fdab\",\"name\":\"madindio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nomloop.com\/uy\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/NomLoop_HOME.webp\",\"contentUrl\":\"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/NomLoop_HOME.webp\",\"width\":468,\"height\":527,\"caption\":\"madindio\"},\"logo\":{\"@id\":\"https:\/\/nomloop.com\/uy\/#\/schema\/person\/image\/\"},\"sameAs\":[\"https:\/\/www.uruservice.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contacto | NomLoop","description":"Contacta con Nomloop para consultas informativas, correcciones de fichas o informaci\u00f3n sobre el directorio de servicios esot\u00e9ricos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nomloop.com\/uy\/contacto\/","og_locale":"es_ES","og_type":"article","og_title":"Contacto | NomLoop","og_description":"Contacta con Nomloop para consultas informativas, correcciones de fichas o informaci\u00f3n sobre el directorio de servicios esot\u00e9ricos.","og_url":"https:\/\/nomloop.com\/uy\/contacto\/","og_site_name":"Uruguay","article_modified_time":"2026-01-31T01:42:29+00:00","og_image":[{"width":1536,"height":572,"url":"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/URUSEGUR_Contacto.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nomloop.com\/uy\/contacto\/","url":"https:\/\/nomloop.com\/uy\/contacto\/","name":"Contacto | NomLoop","isPartOf":{"@id":"https:\/\/nomloop.com\/uy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nomloop.com\/uy\/contacto\/#primaryimage"},"image":{"@id":"https:\/\/nomloop.com\/uy\/contacto\/#primaryimage"},"thumbnailUrl":"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/URUSEGUR_Contacto.webp","datePublished":"2026-01-13T00:28:15+00:00","dateModified":"2026-01-31T01:42:29+00:00","description":"Contacta con Nomloop para consultas informativas, correcciones de fichas o informaci\u00f3n sobre el directorio de servicios esot\u00e9ricos.","breadcrumb":{"@id":"https:\/\/nomloop.com\/uy\/contacto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nomloop.com\/uy\/contacto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nomloop.com\/uy\/contacto\/#primaryimage","url":"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/URUSEGUR_Contacto.webp","contentUrl":"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/URUSEGUR_Contacto.webp","width":1536,"height":572,"caption":"Pre-Contacto"},{"@type":"BreadcrumbList","@id":"https:\/\/nomloop.com\/uy\/contacto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/nomloop.com\/uy\/"},{"@type":"ListItem","position":2,"name":"Contacto"}]},{"@type":"WebSite","@id":"https:\/\/nomloop.com\/uy\/#website","url":"https:\/\/nomloop.com\/uy\/","name":"Uruguay","description":"","publisher":{"@id":"https:\/\/nomloop.com\/uy\/#\/schema\/person\/31d96ea0e6c72ae23ec4f725e949fdab"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nomloop.com\/uy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/nomloop.com\/uy\/#\/schema\/person\/31d96ea0e6c72ae23ec4f725e949fdab","name":"madindio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nomloop.com\/uy\/#\/schema\/person\/image\/","url":"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/NomLoop_HOME.webp","contentUrl":"https:\/\/nomloop.com\/uy\/wp-content\/uploads\/sites\/83\/NomLoop_HOME.webp","width":468,"height":527,"caption":"madindio"},"logo":{"@id":"https:\/\/nomloop.com\/uy\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/www.uruservice.com"]}]}},"_links":{"self":[{"href":"https:\/\/nomloop.com\/uy\/wp-json\/wp\/v2\/pages\/519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nomloop.com\/uy\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nomloop.com\/uy\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nomloop.com\/uy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nomloop.com\/uy\/wp-json\/wp\/v2\/comments?post=519"}],"version-history":[{"count":2,"href":"https:\/\/nomloop.com\/uy\/wp-json\/wp\/v2\/pages\/519\/revisions"}],"predecessor-version":[{"id":703,"href":"https:\/\/nomloop.com\/uy\/wp-json\/wp\/v2\/pages\/519\/revisions\/703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nomloop.com\/uy\/wp-json\/wp\/v2\/media\/509"}],"wp:attachment":[{"href":"https:\/\/nomloop.com\/uy\/wp-json\/wp\/v2\/media?parent=519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}